{"id":409918,"date":"2024-04-19T18:50:48","date_gmt":"2024-04-19T16:50:48","guid":{"rendered":"https:\/\/www.allaboutautomation.de\/products\/rdmup-die-hellste-led-industrie-signalleuchte\/"},"modified":"2024-04-24T21:20:56","modified_gmt":"2024-04-24T19:20:56","slug":"rdmup-die-hellste-led-industrie-signalleuchte","status":"publish","type":"products","link":"https:\/\/www.allaboutautomation.de\/fr\/products\/rdmup-die-hellste-led-industrie-signalleuchte\/","title":{"rendered":"RDMUP &#8211; die hellste LED Industrie-Signalleuchte"},"content":{"rendered":"<p>Es gibt viele Signalleuchten, die in Innenr\u00e4umen Ihre Aufmerksamkeit auf sich ziehen. Signalleuchten im direkten Sonnenlicht hingegen bleiben oftmals unbemerkt.<\/p>\n<p>Unsere Antwort:<br \/>\nDie weltweit hellste industrielle LED-Signalleuchte<\/p>\n<p>RDMUP<br \/>\nSerie R &#8211; Ultra Performance<br \/>\nMit der Einf\u00fchrung der neuen RDM Ultra Performance vervollst\u00e4ndigen wir unsere Serie R mit der hellsten LED Signalleuchte weltweit. Sie ist 2x \u2013 4x heller als jede andere Signalleuchte auf dem Markt und signalisiert auch bei direkter Sonneneinstrahlung zuverl\u00e4ssig vor potentiellen Gefahren.<\/p>\n<p>Anwendungen: RDMUP bietet Sicherheit f\u00fcr Langstreckensignalisierung im Freien: Logistik \/ Kraftwerke \/ H\u00e4fen \/ Eisenbahnsignalisierung auf Privatgrundst\u00fccken \/ Tore \/ gro\u00dfe, bewegliche Maschinen und Anlagen \/ Schwermaschinen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es gibt viele Signalleuchten, die in Innenr\u00e4umen Ihre Aufmerksamkeit auf sich ziehen. Signalleuchten im direkten Sonnenlicht hingegen bleiben oftmals unbemerkt. Unsere Antwort: Die weltweit hellste industrielle LED-Signalleuchte RDMUP Serie R &#8211; Ultra Performance Mit der Einf\u00fchrung der neuen RDM Ultra Performance vervollst\u00e4ndigen wir unsere Serie R mit der hellsten LED Signalleuchte weltweit. Sie ist 2x [&hellip;]<\/p>\n","protected":false},"featured_media":409934,"template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_api_id":"212374","_exhibitors":["312008"],"footnotes":""},"tags":[],"edition":[1803],"product-category":[],"class_list":["post-409918","products","type-products","status-publish","has-post-thumbnail","hentry","edition-all-about-automation-friedrichshafen-24"],"_links":{"self":[{"href":"https:\/\/www.allaboutautomation.de\/fr\/wp-json\/wp\/v2\/products\/409918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.allaboutautomation.de\/fr\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.allaboutautomation.de\/fr\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":1,"href":"https:\/\/www.allaboutautomation.de\/fr\/wp-json\/wp\/v2\/products\/409918\/revisions"}],"predecessor-version":[{"id":410927,"href":"https:\/\/www.allaboutautomation.de\/fr\/wp-json\/wp\/v2\/products\/409918\/revisions\/410927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.allaboutautomation.de\/fr\/wp-json\/wp\/v2\/media\/409934"}],"wp:attachment":[{"href":"https:\/\/www.allaboutautomation.de\/fr\/wp-json\/wp\/v2\/media?parent=409918"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.allaboutautomation.de\/fr\/wp-json\/wp\/v2\/tags?post=409918"},{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.allaboutautomation.de\/fr\/wp-json\/wp\/v2\/edition?post=409918"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/www.allaboutautomation.de\/fr\/wp-json\/wp\/v2\/product-category?post=409918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}